{"id":4500,"date":"2024-09-19T12:11:19","date_gmt":"2024-09-19T12:11:19","guid":{"rendered":"https:\/\/cablepullingmachines.com\/fabricante-de-remolques-de-bobinas-de-cable\/"},"modified":"2024-09-19T12:11:20","modified_gmt":"2024-09-19T12:11:20","slug":"fabricante-de-remolques-de-bobinas-de-cable","status":"publish","type":"post","link":"https:\/\/cablepullingmachines.com\/es\/fabricante-de-remolques-de-bobinas-de-cable\/","title":{"rendered":"\u00a1Fabricante de remolques de bobinas de cable!"},"content":{"rendered":"<h1><strong>Fabricante de remolques de bobinas de cable<\/strong><\/h1>\n<p><strong>Consigue lo mejor en accesorios para remolques de cable  <\/strong><\/p>\n<p><strong><em>Las bobinas de cable son una parte muy esencial de una unidad de tracci\u00f3n de cables, ya que ayudan a fabricar unidades que pueden alojar bobinas de cable que son pesadas y no se pueden mover por s\u00ed solas.<br \/>\nAyudan a transportar cables de cobre duro y de la mejor calidad que son dif\u00edciles de mover de una parte a otra. <\/em><\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Qu\u00e9 son las m\u00e1quinas de tracci\u00f3n de cables<\/strong>&nbsp; Las m\u00e1quinas de tracci\u00f3n de cables son los equipos de mayor calidad que no s\u00f3lo son fiables y eficaces para este fin, sino que tambi\u00e9n te proporcionan el mejor m\u00e9todo rentable para tender todos tus cables durante varios a\u00f1os.<br \/>\nSon resistentes, duraderos y seguros de usar.<br \/>\nAlgunos de los mejores cabrestantes de tracci\u00f3n por cable se dise\u00f1an seg\u00fan tus necesidades y se personalizan en consecuencia seg\u00fan tus requisitos.<br \/>\nSon necesarios para diversos proyectos, tanto fuera como dentro de las instalaciones. <strong>Especificaci\u00f3n de una m\u00e1quina de tracci\u00f3n por cable <\/strong> La especificaci\u00f3n m\u00e1s com\u00fan de un cabrestante de tracci\u00f3n por cable es Unidad de potencia: Motor diesel de 13 kW a 3.600 rpm, Sistema de accionamiento principal: Cabrestante simple, Accionamiento del tambor de rebobinado: Accionamiento hidr\u00e1ulico para la tensi\u00f3n del cable, Salida del cable: Bobinado libre, Indicador de carga de tracci\u00f3n: Indicador de presi\u00f3n\/tonelada de tracci\u00f3n: Equipado con ventilador termost\u00e1tico.<br \/>\nTambor de rebobinado: 400 m de cable de 10 mm de di\u00e1metro (m\u00e1x.).<br \/>\nColocaci\u00f3n de la cuerda: Brazo de tendido de movimiento libre (montado debajo del tambor de rebobinado).<br \/>\nTracci\u00f3n del cable\/velocidad: 0,5 toneladas &#8211; 30 mtr\/min 1,5 toneladas &#8211; 22 mtr\/min 3,0 toneladas &#8211; 7 mtr\/min <strong>Por qu\u00e9 las m\u00e1quinas de tracci\u00f3n de cable son tan conocidas porFabricante de remolques para bobinas de cable <\/strong> Nosotros, como<strong>fabricantes de remolques para bobinas de<\/strong> cable<strong>,<\/strong> nos aseguramos de que el remolque pueda transportar bobinas de varios tama\u00f1os con cable.<br \/>\nNuestra empresa cuenta con un gran n\u00famero de m\u00e1quinas hidr\u00e1ulicas y el\u00e9ctricas de cable que contribuyen a que el trabajo y el rendimiento sean fluidos.<br \/>\nTodos nuestros equipos est\u00e1n fabricados con la \u00faltima tecnolog\u00eda actualizada y nosotros, como<strong>fabricantes de <\/strong>  <em>remolques<\/em> para<strong>bobinas de <\/strong>cable, nos centramos en los mejores materiales. Puedes comprar algunos de los mejores remolques para bobinas de cable en nuestro sitio web. Nuestros productos son asequibles, fiables, seguros y de buena calidad. Vis\u00edtanos si buscas equipos de tracci\u00f3n por cable de buena calidad. <figure id=\"attachment_522\" aria-describedby=\"caption-attachment-522\" style=\"width: 1000px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" class=\"size-full wp-image-522 lazyload\" data-src=\"http:\/\/cablepullingmachines.com\/wp-content\/uploads\/2016\/10\/Cable-Drum-Trailers-Manufacturer.jpg\" alt=\"fabricante de remolques de bobinas de cable\" width=\"1000\" height=\"750\" data-srcset=\"https:\/\/cablepullingmachines.com\/wp-content\/uploads\/2016\/10\/Cable-Drum-Trailers-Manufacturer.jpg 1000w, https:\/\/cablepullingmachines.com\/wp-content\/uploads\/2016\/10\/Cable-Drum-Trailers-Manufacturer-300x225.jpg 300w, https:\/\/cablepullingmachines.com\/wp-content\/uploads\/2016\/10\/Cable-Drum-Trailers-Manufacturer-768x576.jpg 768w, https:\/\/cablepullingmachines.com\/wp-content\/uploads\/2016\/10\/Cable-Drum-Trailers-Manufacturer-705x529.jpg 705w, https:\/\/cablepullingmachines.com\/wp-content\/uploads\/2016\/10\/Cable-Drum-Trailers-Manufacturer-450x338.jpg 450w\" data-sizes=\"(max-width: 1000px) 100vw, 1000px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1000px; --smush-placeholder-aspect-ratio: 1000\/750;\" \/><figcaption id=\"caption-attachment-522\" class=\"wp-caption-text\">fabricante de <em>remolques para bobinas de cable<\/em><\/figcaption><\/figure>        <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fabricante de remolques de bobinas de cable Consigue lo mejor en accesorios para remolques de cable Las bobinas de cable son una parte muy esencial de una unidad de tracci\u00f3n de cables, ya que ayudan a fabricar unidades que pueden alojar bobinas de cable que son pesadas y no se pueden mover por s\u00ed solas.<\/p>\n","protected":false},"author":1,"featured_media":2930,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[108],"tags":[159,158,161,160],"class_list":["post-4500","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-remolques-de-cable","tag-fabricante-de-remolques-de-bobinas-de-cable","tag-maquinas-de-traccion-por-cable","tag-remolques-de-bidones","tag-tambores"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>\u00a1Fabricante de remolques de bobinas de cable! - Cable Pulling Machines Manufacturer<\/title>\n<meta name=\"description\" content=\"Cable Pulling Machines Manufacturer -\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cablepullingmachines.com\/es\/?p=4500\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00a1Fabricante de remolques de bobinas de cable!\" \/>\n<meta property=\"og:description\" content=\"Cable Pulling Machines Manufacturer -\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cablepullingmachines.com\/es\/?p=4500\" \/>\n<meta property=\"og:site_name\" content=\"Cable Pulling Machines Manufacturer\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/cablepullingmachines\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-19T12:11:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-19T12:11:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/cablepullingmachines.com\/wp-content\/uploads\/2016\/10\/Cable-Drum-Trailers-Manufacturer.jpg?fit=1000%2C750&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"750\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"erkan1095\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"erkan1095\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cablepullingmachines.com\\\/es\\\/?p=4500#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cablepullingmachines.com\\\/es\\\/?p=4500\"},\"author\":{\"name\":\"erkan1095\",\"@id\":\"https:\\\/\\\/cablepullingmachines.com\\\/#\\\/schema\\\/person\\\/adee820dbf697557a02001f9d5cfef65\"},\"headline\":\"\u00a1Fabricante de remolques de bobinas de cable!\",\"datePublished\":\"2024-09-19T12:11:19+00:00\",\"dateModified\":\"2024-09-19T12:11:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cablepullingmachines.com\\\/es\\\/?p=4500\"},\"wordCount\":472,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/cablepullingmachines.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/cablepullingmachines.com\\\/es\\\/?p=4500#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cablepullingmachines.com\\\/wp-content\\\/uploads\\\/2016\\\/10\\\/Cable-Drum-Trailers-Manufacturer.jpg\",\"keywords\":[\"Fabricante de remolques de bobinas de cable\",\"m\u00e1quinas de tracci\u00f3n por cable\",\"remolques de bidones\",\"tambores\"],\"articleSection\":[\"Remolques de Cable\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/cablepullingmachines.com\\\/es\\\/?p=4500#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cablepullingmachines.com\\\/es\\\/?p=4500\",\"url\":\"https:\\\/\\\/cablepullingmachines.com\\\/es\\\/?p=4500\",\"name\":\"\u00a1Fabricante de remolques de bobinas de cable! - Cable Pulling Machines Manufacturer\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cablepullingmachines.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cablepullingmachines.com\\\/es\\\/?p=4500#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cablepullingmachines.com\\\/es\\\/?p=4500#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cablepullingmachines.com\\\/wp-content\\\/uploads\\\/2016\\\/10\\\/Cable-Drum-Trailers-Manufacturer.jpg\",\"datePublished\":\"2024-09-19T12:11:19+00:00\",\"dateModified\":\"2024-09-19T12:11:20+00:00\",\"description\":\"Cable Pulling Machines Manufacturer -\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cablepullingmachines.com\\\/es\\\/?p=4500#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cablepullingmachines.com\\\/es\\\/?p=4500\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/cablepullingmachines.com\\\/es\\\/?p=4500#primaryimage\",\"url\":\"https:\\\/\\\/cablepullingmachines.com\\\/wp-content\\\/uploads\\\/2016\\\/10\\\/Cable-Drum-Trailers-Manufacturer.jpg\",\"contentUrl\":\"https:\\\/\\\/cablepullingmachines.com\\\/wp-content\\\/uploads\\\/2016\\\/10\\\/Cable-Drum-Trailers-Manufacturer.jpg\",\"width\":1000,\"height\":750,\"caption\":\"cable drum trailer manufacturer\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cablepullingmachines.com\\\/es\\\/?p=4500#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/cablepullingmachines.com\\\/es\\\/a\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00a1Fabricante de remolques de bobinas de cable!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cablepullingmachines.com\\\/#website\",\"url\":\"https:\\\/\\\/cablepullingmachines.com\\\/\",\"name\":\"Cable Pulling Machines and Cable Drum Trailers\",\"description\":\"Cable Pulling Machines, Winches, Cable Drum Trailers\",\"publisher\":{\"@id\":\"https:\\\/\\\/cablepullingmachines.com\\\/#organization\"},\"alternateName\":\"Cable Drum Trailers Manufacturer\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cablepullingmachines.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cablepullingmachines.com\\\/#organization\",\"name\":\"Allame Makina Ltd Sti\",\"alternateName\":\"Cable Drum Trailers Manufacturer\",\"url\":\"https:\\\/\\\/cablepullingmachines.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/cablepullingmachines.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cablepullingmachines.com\\\/wp-content\\\/uploads\\\/2015\\\/10\\\/logo.jpg\",\"contentUrl\":\"https:\\\/\\\/cablepullingmachines.com\\\/wp-content\\\/uploads\\\/2015\\\/10\\\/logo.jpg\",\"width\":300,\"height\":140,\"caption\":\"Allame Makina Ltd Sti\"},\"image\":{\"@id\":\"https:\\\/\\\/cablepullingmachines.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/cablepullingmachines\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/cablepullingmachines\",\"https:\\\/\\\/www.youtube.com\\\/@CablePullingMachines\",\"https:\\\/\\\/www.instagram.com\\\/cablepullingmachines\"],\"description\":\"Cable laying products manufacturer from Turkiye. Cable Pulling Machines and Cable Drum Trailers Producer.\",\"email\":\"erkangok@allame.net\",\"telephone\":\"+905337789941\",\"legalName\":\"SKYPULLTECH\",\"foundingDate\":\"1999-02-12\",\"vatID\":\"0550635748\",\"iso6523Code\":\"1555ALL2025\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"11\",\"maxValue\":\"50\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cablepullingmachines.com\\\/#\\\/schema\\\/person\\\/adee820dbf697557a02001f9d5cfef65\",\"name\":\"erkan1095\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6873feb1b5825afbd9e3843a10900d3690ccdd37d43b0ebe87f66d02c31bb39a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6873feb1b5825afbd9e3843a10900d3690ccdd37d43b0ebe87f66d02c31bb39a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6873feb1b5825afbd9e3843a10900d3690ccdd37d43b0ebe87f66d02c31bb39a?s=96&d=mm&r=g\",\"caption\":\"erkan1095\"},\"url\":\"https:\\\/\\\/cablepullingmachines.com\\\/es\\\/author\\\/erkan1095\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u00a1Fabricante de remolques de bobinas de cable! - Cable Pulling Machines Manufacturer","description":"Cable Pulling Machines Manufacturer -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cablepullingmachines.com\/es\/?p=4500","og_locale":"es_ES","og_type":"article","og_title":"\u00a1Fabricante de remolques de bobinas de cable!","og_description":"Cable Pulling Machines Manufacturer -","og_url":"https:\/\/cablepullingmachines.com\/es\/?p=4500","og_site_name":"Cable Pulling Machines Manufacturer","article_publisher":"https:\/\/www.facebook.com\/cablepullingmachines","article_published_time":"2024-09-19T12:11:19+00:00","article_modified_time":"2024-09-19T12:11:20+00:00","og_image":[{"width":1000,"height":750,"url":"https:\/\/i0.wp.com\/cablepullingmachines.com\/wp-content\/uploads\/2016\/10\/Cable-Drum-Trailers-Manufacturer.jpg?fit=1000%2C750&ssl=1","type":"image\/jpeg"}],"author":"erkan1095","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"erkan1095","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cablepullingmachines.com\/es\/?p=4500#article","isPartOf":{"@id":"https:\/\/cablepullingmachines.com\/es\/?p=4500"},"author":{"name":"erkan1095","@id":"https:\/\/cablepullingmachines.com\/#\/schema\/person\/adee820dbf697557a02001f9d5cfef65"},"headline":"\u00a1Fabricante de remolques de bobinas de cable!","datePublished":"2024-09-19T12:11:19+00:00","dateModified":"2024-09-19T12:11:20+00:00","mainEntityOfPage":{"@id":"https:\/\/cablepullingmachines.com\/es\/?p=4500"},"wordCount":472,"commentCount":0,"publisher":{"@id":"https:\/\/cablepullingmachines.com\/#organization"},"image":{"@id":"https:\/\/cablepullingmachines.com\/es\/?p=4500#primaryimage"},"thumbnailUrl":"https:\/\/cablepullingmachines.com\/wp-content\/uploads\/2016\/10\/Cable-Drum-Trailers-Manufacturer.jpg","keywords":["Fabricante de remolques de bobinas de cable","m\u00e1quinas de tracci\u00f3n por cable","remolques de bidones","tambores"],"articleSection":["Remolques de Cable"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/cablepullingmachines.com\/es\/?p=4500#respond"]}]},{"@type":"WebPage","@id":"https:\/\/cablepullingmachines.com\/es\/?p=4500","url":"https:\/\/cablepullingmachines.com\/es\/?p=4500","name":"\u00a1Fabricante de remolques de bobinas de cable! - Cable Pulling Machines Manufacturer","isPartOf":{"@id":"https:\/\/cablepullingmachines.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cablepullingmachines.com\/es\/?p=4500#primaryimage"},"image":{"@id":"https:\/\/cablepullingmachines.com\/es\/?p=4500#primaryimage"},"thumbnailUrl":"https:\/\/cablepullingmachines.com\/wp-content\/uploads\/2016\/10\/Cable-Drum-Trailers-Manufacturer.jpg","datePublished":"2024-09-19T12:11:19+00:00","dateModified":"2024-09-19T12:11:20+00:00","description":"Cable Pulling Machines Manufacturer -","breadcrumb":{"@id":"https:\/\/cablepullingmachines.com\/es\/?p=4500#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cablepullingmachines.com\/es\/?p=4500"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cablepullingmachines.com\/es\/?p=4500#primaryimage","url":"https:\/\/cablepullingmachines.com\/wp-content\/uploads\/2016\/10\/Cable-Drum-Trailers-Manufacturer.jpg","contentUrl":"https:\/\/cablepullingmachines.com\/wp-content\/uploads\/2016\/10\/Cable-Drum-Trailers-Manufacturer.jpg","width":1000,"height":750,"caption":"cable drum trailer manufacturer"},{"@type":"BreadcrumbList","@id":"https:\/\/cablepullingmachines.com\/es\/?p=4500#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cablepullingmachines.com\/es\/a\/"},{"@type":"ListItem","position":2,"name":"\u00a1Fabricante de remolques de bobinas de cable!"}]},{"@type":"WebSite","@id":"https:\/\/cablepullingmachines.com\/#website","url":"https:\/\/cablepullingmachines.com\/","name":"Cable Pulling Machines and Cable Drum Trailers","description":"Cable Pulling Machines, Winches, Cable Drum Trailers","publisher":{"@id":"https:\/\/cablepullingmachines.com\/#organization"},"alternateName":"Cable Drum Trailers Manufacturer","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cablepullingmachines.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/cablepullingmachines.com\/#organization","name":"Allame Makina Ltd Sti","alternateName":"Cable Drum Trailers Manufacturer","url":"https:\/\/cablepullingmachines.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cablepullingmachines.com\/#\/schema\/logo\/image\/","url":"https:\/\/cablepullingmachines.com\/wp-content\/uploads\/2015\/10\/logo.jpg","contentUrl":"https:\/\/cablepullingmachines.com\/wp-content\/uploads\/2015\/10\/logo.jpg","width":300,"height":140,"caption":"Allame Makina Ltd Sti"},"image":{"@id":"https:\/\/cablepullingmachines.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/cablepullingmachines","https:\/\/www.linkedin.com\/company\/cablepullingmachines","https:\/\/www.youtube.com\/@CablePullingMachines","https:\/\/www.instagram.com\/cablepullingmachines"],"description":"Cable laying products manufacturer from Turkiye. Cable Pulling Machines and Cable Drum Trailers Producer.","email":"erkangok@allame.net","telephone":"+905337789941","legalName":"SKYPULLTECH","foundingDate":"1999-02-12","vatID":"0550635748","iso6523Code":"1555ALL2025","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"11","maxValue":"50"}},{"@type":"Person","@id":"https:\/\/cablepullingmachines.com\/#\/schema\/person\/adee820dbf697557a02001f9d5cfef65","name":"erkan1095","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/6873feb1b5825afbd9e3843a10900d3690ccdd37d43b0ebe87f66d02c31bb39a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6873feb1b5825afbd9e3843a10900d3690ccdd37d43b0ebe87f66d02c31bb39a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6873feb1b5825afbd9e3843a10900d3690ccdd37d43b0ebe87f66d02c31bb39a?s=96&d=mm&r=g","caption":"erkan1095"},"url":"https:\/\/cablepullingmachines.com\/es\/author\/erkan1095\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/cablepullingmachines.com\/es\/wp-json\/wp\/v2\/posts\/4500","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cablepullingmachines.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cablepullingmachines.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cablepullingmachines.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cablepullingmachines.com\/es\/wp-json\/wp\/v2\/comments?post=4500"}],"version-history":[{"count":0,"href":"https:\/\/cablepullingmachines.com\/es\/wp-json\/wp\/v2\/posts\/4500\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cablepullingmachines.com\/es\/wp-json\/wp\/v2\/media\/2930"}],"wp:attachment":[{"href":"https:\/\/cablepullingmachines.com\/es\/wp-json\/wp\/v2\/media?parent=4500"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cablepullingmachines.com\/es\/wp-json\/wp\/v2\/categories?post=4500"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cablepullingmachines.com\/es\/wp-json\/wp\/v2\/tags?post=4500"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}